{"id":10215,"date":"2026-01-25T11:54:10","date_gmt":"2026-01-25T11:54:10","guid":{"rendered":"https:\/\/mecal.net\/products\/uncategorized\/fmky\/"},"modified":"2026-06-02T07:01:12","modified_gmt":"2026-06-02T07:01:12","slug":"fmky","status":"publish","type":"product","link":"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/","title":{"rendered":"FMKY"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text css=&#8221;&#8221;]<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td><strong>Edition<\/strong><\/td>\n<td>Magnum FMKY<\/td>\n<\/tr>\n<tr>\n<td><strong>Feed<\/strong><\/td>\n<td>Front-feed<\/td>\n<\/tr>\n<tr>\n<td><strong>Feed system<\/strong><\/td>\n<td>Manual insertion<\/td>\n<\/tr>\n<tr>\n<td><strong>Working height<\/strong><\/td>\n<td>190 \u00b10.02 mm (7.48 in)<\/td>\n<\/tr>\n<tr>\n<td><strong>Stroke<\/strong><\/td>\n<td>40 mm (1.57 in)<\/td>\n<\/tr>\n<tr>\n<td><strong>Cable cross-section<\/strong><\/td>\n<td>Max. 16 mm\u00b2 (5 AWG)<\/td>\n<\/tr>\n<tr>\n<td><strong>Terminal diameter<\/strong><\/td>\n<td>Max. \u00d810 mm (0.39 in)<\/td>\n<\/tr>\n<tr>\n<td><strong>Terminal length<\/strong><\/td>\n<td>Max. 60 mm (2.36 in)<\/td>\n<\/tr>\n<tr>\n<td><strong>Terminal pitch<\/strong><\/td>\n<td>Loose terminals<\/td>\n<\/tr>\n<tr>\n<td><strong>Terminal thickness<\/strong><\/td>\n<td>Max. 1.6 mm (0.06 in)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/vc_column_text][vc_empty_space][vc_column_text css=&#8221;&#8221;]<\/p>\n<h6 class=\"title-holder clearfix description_tab ui-accordion-header-active ui-state-active ui-accordion-header ui-helper-reset ui-state-default ui-corner-top ui-corner-bottom\">Description<\/h6>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;10px&#8221;][vc_column_text css=&#8221;&#8221;]FMKY combines FMK power with Y-type connection, optimized for specific machines. Designed for large tubular terminals, it ensures uniform and centered crimps in demanding industrial applications.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[button size=\"medium\" icon_pack=\"font_awesome_5\" font_awesome_5=\"fa fa-file-pdf\" target=\"_blank\" hover_type=\"default\" text=\"Datasheet\" link=\"https:\/\/doc.mecal.net\/public\/Datasheet FMKY_EN.pdf\"][vc_column_text css=&#8221;&#8221;]<\/p>\n","protected":false},"featured_media":10210,"template":"","meta":[],"product_brand":[],"product_cat":[87,98],"product_tag":[],"class_list":{"0":"post-10215","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-applicators","7":"product_cat-4-point-crimp","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FMKY - Mecal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FMKY - Mecal\" \/>\n<meta property=\"og:description\" content=\"[vc_column_text css=&quot;&quot;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/\" \/>\n<meta property=\"og:site_name\" content=\"Mecal\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T07:01:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mecal.net\/wp-content\/uploads\/2026\/01\/FMKY-00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/\",\"url\":\"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/\",\"name\":\"FMKY - Mecal\",\"isPartOf\":{\"@id\":\"https:\/\/mecal.net\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mecal.net\/wp-content\/uploads\/2026\/01\/FMKY-00.jpg\",\"datePublished\":\"2026-01-25T11:54:10+00:00\",\"dateModified\":\"2026-06-02T07:01:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/#primaryimage\",\"url\":\"https:\/\/mecal.net\/wp-content\/uploads\/2026\/01\/FMKY-00.jpg\",\"contentUrl\":\"https:\/\/mecal.net\/wp-content\/uploads\/2026\/01\/FMKY-00.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"FMKY\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mecal.net\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/mecal.net\/en\/products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Applicators\",\"item\":\"https:\/\/mecal.net\/en\/products\/applicators\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"FMKY\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mecal.net\/en\/#website\",\"url\":\"https:\/\/mecal.net\/en\/\",\"name\":\"Mecal\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mecal.net\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FMKY - Mecal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/","og_locale":"en_US","og_type":"article","og_title":"FMKY - Mecal","og_description":"[vc_column_text css=\"\"]","og_url":"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/","og_site_name":"Mecal","article_modified_time":"2026-06-02T07:01:12+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/mecal.net\/wp-content\/uploads\/2026\/01\/FMKY-00.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/","url":"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/","name":"FMKY - Mecal","isPartOf":{"@id":"https:\/\/mecal.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/#primaryimage"},"image":{"@id":"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/#primaryimage"},"thumbnailUrl":"https:\/\/mecal.net\/wp-content\/uploads\/2026\/01\/FMKY-00.jpg","datePublished":"2026-01-25T11:54:10+00:00","dateModified":"2026-06-02T07:01:12+00:00","breadcrumb":{"@id":"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mecal.net\/en\/products\/applicators\/fmky\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/#primaryimage","url":"https:\/\/mecal.net\/wp-content\/uploads\/2026\/01\/FMKY-00.jpg","contentUrl":"https:\/\/mecal.net\/wp-content\/uploads\/2026\/01\/FMKY-00.jpg","width":1200,"height":1200,"caption":"FMKY"},{"@type":"BreadcrumbList","@id":"https:\/\/mecal.net\/en\/products\/applicators\/fmky\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mecal.net\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/mecal.net\/en\/products\/"},{"@type":"ListItem","position":3,"name":"Applicators","item":"https:\/\/mecal.net\/en\/products\/applicators\/"},{"@type":"ListItem","position":4,"name":"FMKY"}]},{"@type":"WebSite","@id":"https:\/\/mecal.net\/en\/#website","url":"https:\/\/mecal.net\/en\/","name":"Mecal","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mecal.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/mecal.net\/en\/wp-json\/wp\/v2\/product\/10215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mecal.net\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mecal.net\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mecal.net\/en\/wp-json\/wp\/v2\/media\/10210"}],"wp:attachment":[{"href":"https:\/\/mecal.net\/en\/wp-json\/wp\/v2\/media?parent=10215"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mecal.net\/en\/wp-json\/wp\/v2\/product_brand?post=10215"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mecal.net\/en\/wp-json\/wp\/v2\/product_cat?post=10215"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mecal.net\/en\/wp-json\/wp\/v2\/product_tag?post=10215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}